{"id":6531,"date":"2025-08-18T16:24:13","date_gmt":"2025-08-18T14:24:13","guid":{"rendered":"https:\/\/schoolofvoice.berlin\/de\/?page_id=6531"},"modified":"2025-08-18T16:24:14","modified_gmt":"2025-08-18T14:24:14","slug":"anastasia-fugger","status":"publish","type":"page","link":"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/anastasia-fugger\/","title":{"rendered":"Anastasia Fugger"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":6533,"parent":170,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[175,142,179],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Anastasia Fugger - School Of Voice<\/title>\n<meta name=\"description\" content=\"Dozentin an der Kara Johnstad School Of Voice | Anastasia Fugger ist zertifizierte Klangtherapeutin, Musikforscherin, S\u00e4ngerin und vielseitige Kreative. Sie verbindet spontanes Musizieren, fantasievolles Spiel und intuitive K\u00f6rper-Geist-\u00dcbungen, um die wundersamen Geheimnisse des Klangs und der menschlichen Stimme zu erforschen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/anastasia-fugger\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anastasia Fugger - School Of Voice\" \/>\n<meta property=\"og:description\" content=\"Dozentin an der Kara Johnstad School Of Voice | Anastasia Fugger ist zertifizierte Klangtherapeutin, Musikforscherin, S\u00e4ngerin und vielseitige Kreative. Sie verbindet spontanes Musizieren, fantasievolles Spiel und intuitive K\u00f6rper-Geist-\u00dcbungen, um die wundersamen Geheimnisse des Klangs und der menschlichen Stimme zu erforschen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/anastasia-fugger\/\" \/>\n<meta property=\"og:site_name\" content=\"School Of Voice\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-18T14:24:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/schoolofvoice.berlin\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/SoV_Anastasia-Fugger_450-x-526-px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"526\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/anastasia-fugger\/\",\"url\":\"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/anastasia-fugger\/\",\"name\":\"Anastasia Fugger - School Of Voice\",\"isPartOf\":{\"@id\":\"https:\/\/schoolofvoice.berlin\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/anastasia-fugger\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/anastasia-fugger\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/schoolofvoice.berlin\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/SoV_Anastasia-Fugger_450-x-526-px.jpg\",\"datePublished\":\"2025-08-18T14:24:13+00:00\",\"dateModified\":\"2025-08-18T14:24:14+00:00\",\"description\":\"Dozentin an der Kara Johnstad School Of Voice | Anastasia Fugger ist zertifizierte Klangtherapeutin, Musikforscherin, S\u00e4ngerin und vielseitige Kreative. Sie verbindet spontanes Musizieren, fantasievolles Spiel und intuitive K\u00f6rper-Geist-\u00dcbungen, um die wundersamen Geheimnisse des Klangs und der menschlichen Stimme zu erforschen.\",\"breadcrumb\":{\"@id\":\"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/anastasia-fugger\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/anastasia-fugger\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/anastasia-fugger\/#primaryimage\",\"url\":\"https:\/\/schoolofvoice.berlin\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/SoV_Anastasia-Fugger_450-x-526-px.jpg\",\"contentUrl\":\"https:\/\/schoolofvoice.berlin\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/SoV_Anastasia-Fugger_450-x-526-px.jpg\",\"width\":450,\"height\":526,\"caption\":\"Anastasia Fugger | Dozentin an der Kara Johnstad School Of Voice\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/anastasia-fugger\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/schoolofvoice.berlin\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00dcber uns\",\"item\":\"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Unsere Lehrer:innen\",\"item\":\"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Anastasia Fugger\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/schoolofvoice.berlin\/de\/#website\",\"url\":\"https:\/\/schoolofvoice.berlin\/de\/\",\"name\":\"School Of Voice\",\"description\":\"Vocal Coaching - Music Lessons - Artist Development\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/schoolofvoice.berlin\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anastasia Fugger - School Of Voice","description":"Dozentin an der Kara Johnstad School Of Voice | Anastasia Fugger ist zertifizierte Klangtherapeutin, Musikforscherin, S\u00e4ngerin und vielseitige Kreative. Sie verbindet spontanes Musizieren, fantasievolles Spiel und intuitive K\u00f6rper-Geist-\u00dcbungen, um die wundersamen Geheimnisse des Klangs und der menschlichen Stimme zu erforschen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/anastasia-fugger\/","og_locale":"de_DE","og_type":"article","og_title":"Anastasia Fugger - School Of Voice","og_description":"Dozentin an der Kara Johnstad School Of Voice | Anastasia Fugger ist zertifizierte Klangtherapeutin, Musikforscherin, S\u00e4ngerin und vielseitige Kreative. Sie verbindet spontanes Musizieren, fantasievolles Spiel und intuitive K\u00f6rper-Geist-\u00dcbungen, um die wundersamen Geheimnisse des Klangs und der menschlichen Stimme zu erforschen.","og_url":"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/anastasia-fugger\/","og_site_name":"School Of Voice","article_modified_time":"2025-08-18T14:24:14+00:00","og_image":[{"width":450,"height":526,"url":"https:\/\/schoolofvoice.berlin\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/SoV_Anastasia-Fugger_450-x-526-px.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1 Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/anastasia-fugger\/","url":"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/anastasia-fugger\/","name":"Anastasia Fugger - School Of Voice","isPartOf":{"@id":"https:\/\/schoolofvoice.berlin\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/anastasia-fugger\/#primaryimage"},"image":{"@id":"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/anastasia-fugger\/#primaryimage"},"thumbnailUrl":"https:\/\/schoolofvoice.berlin\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/SoV_Anastasia-Fugger_450-x-526-px.jpg","datePublished":"2025-08-18T14:24:13+00:00","dateModified":"2025-08-18T14:24:14+00:00","description":"Dozentin an der Kara Johnstad School Of Voice | Anastasia Fugger ist zertifizierte Klangtherapeutin, Musikforscherin, S\u00e4ngerin und vielseitige Kreative. Sie verbindet spontanes Musizieren, fantasievolles Spiel und intuitive K\u00f6rper-Geist-\u00dcbungen, um die wundersamen Geheimnisse des Klangs und der menschlichen Stimme zu erforschen.","breadcrumb":{"@id":"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/anastasia-fugger\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/anastasia-fugger\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/anastasia-fugger\/#primaryimage","url":"https:\/\/schoolofvoice.berlin\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/SoV_Anastasia-Fugger_450-x-526-px.jpg","contentUrl":"https:\/\/schoolofvoice.berlin\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/SoV_Anastasia-Fugger_450-x-526-px.jpg","width":450,"height":526,"caption":"Anastasia Fugger | Dozentin an der Kara Johnstad School Of Voice"},{"@type":"BreadcrumbList","@id":"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/anastasia-fugger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/schoolofvoice.berlin\/de\/"},{"@type":"ListItem","position":2,"name":"\u00dcber uns","item":"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/"},{"@type":"ListItem","position":3,"name":"Unsere Lehrer:innen","item":"https:\/\/schoolofvoice.berlin\/de\/ueber-uns\/lehrer\/"},{"@type":"ListItem","position":4,"name":"Anastasia Fugger"}]},{"@type":"WebSite","@id":"https:\/\/schoolofvoice.berlin\/de\/#website","url":"https:\/\/schoolofvoice.berlin\/de\/","name":"School Of Voice","description":"Vocal Coaching - Music Lessons - Artist Development","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/schoolofvoice.berlin\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"}]}},"_links":{"self":[{"href":"https:\/\/schoolofvoice.berlin\/de\/wp-json\/wp\/v2\/pages\/6531"}],"collection":[{"href":"https:\/\/schoolofvoice.berlin\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/schoolofvoice.berlin\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/schoolofvoice.berlin\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/schoolofvoice.berlin\/de\/wp-json\/wp\/v2\/comments?post=6531"}],"version-history":[{"count":1,"href":"https:\/\/schoolofvoice.berlin\/de\/wp-json\/wp\/v2\/pages\/6531\/revisions"}],"predecessor-version":[{"id":6534,"href":"https:\/\/schoolofvoice.berlin\/de\/wp-json\/wp\/v2\/pages\/6531\/revisions\/6534"}],"up":[{"embeddable":true,"href":"https:\/\/schoolofvoice.berlin\/de\/wp-json\/wp\/v2\/pages\/170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/schoolofvoice.berlin\/de\/wp-json\/wp\/v2\/media\/6533"}],"wp:attachment":[{"href":"https:\/\/schoolofvoice.berlin\/de\/wp-json\/wp\/v2\/media?parent=6531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schoolofvoice.berlin\/de\/wp-json\/wp\/v2\/categories?post=6531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}